{"id":52719,"date":"2019-02-22T14:09:20","date_gmt":"2019-02-22T17:09:20","guid":{"rendered":"https:\/\/www.lanusnoticias.com.ar\/web\/?p=52719"},"modified":"2019-02-22T14:10:02","modified_gmt":"2019-02-22T17:10:02","slug":"lucura-en-lanus-mato-a-su-mujer-y-se-suicido","status":"publish","type":"post","link":"https:\/\/www.lanusnoticias.com.ar\/web\/lucura-en-lanus-mato-a-su-mujer-y-se-suicido\/","title":{"rendered":"LOCURA EN LANUS: MATO A SU MUJER Y SE SUICIDO"},"content":{"rendered":"<p>Ocurri\u00f3 en las calles Jos\u00e9 Le\u00f3n Su\u00e1rez y Dardo Rocha. La v\u00edctima del femicido fue identificada como Anal\u00eda Gauna, de 46 a\u00f1os. El agresor, dos a\u00f1os mayor, la asesin\u00f3 a balazos dentro de una vivienda. En la vereda bale\u00f3 a un vecino que quiso ayudar a la mujer. Luego se peg\u00f3 un tiro en la cabeza y muri\u00f3.<br \/>\nUna mujer de 46 a\u00f1os fue asesinada a balazos esta ma\u00f1ana por su novio, un hombre de 48 a\u00f1os, dentro de su casa ubicada en la localidad bonaerense de Remedios de Escalada, y luego del femicidio el agresor bale\u00f3 a un vecino que quiso ayudar a la mujer y finalmente se suicid\u00f3 de un tiro en la cabeza, informaron fuentes policiales a INFOCIELO.<\/p>\n<p>El brutal hecho se produjo hoy en las calles Jos\u00e9 Le\u00f3n Su\u00e1rez y dardo Rocha cuando por motivos que se investigan, Alejandro Saraceni, de 48 a\u00f1os, ingres\u00f3 a la casa y atac\u00f3 a balazos a Anal\u00eda Gauna, de 46, su novia.<\/p>\n<p>Saraceni sali\u00f3 a la vereda y deton\u00f3 su arma de fuego apuntando al cielo y cuando apareci\u00f3 un vecino, due\u00f1o de un corral\u00f3n lindero, con intenciones de ayudar a la mujer, le peg\u00f3 dos disparos: uno en el pecho y otro en el abdomen.<\/p>\n<p>En medio de esa escena sangrienta, el agresor se coloc\u00f3 la punta del ca\u00f1o en la sien y se suicid\u00f3 de un tiro.<\/p>\n<p>Enseguida llegaron al lugar efectivos del Comando de Patrullas y de la comisar\u00eda Cuarta de Lan\u00fas y encontraron a Anal\u00eda fallecida y al vecino, H\u00e9ctor Parrilla, muy mal herido, por lo que una ambulancia lo traslad\u00f3 de urgencia al Hospital Evita.<\/p>\n<p>En la vivienda de Saraneci los detectives encontraron dos carabinas, dos escopetas, coca\u00edna, marihuana y una balanza de precisi\u00f3n, por lo que se presume que el autor del femicidio era un tranza.<\/p>\n<p>Interviene en la pesquisa la UFI N\u00b0 4 de Lomas de Zamora, desde donde iniciaron actuaciones por los delitos de homicidio, lesiones graves y suicidio.<\/p>\n<p>En lo que va del a\u00f1o, se registran al menos 36 mujeres asesinadas, dando cuenta de uuna in\u00e9dita emergencia en materia de violencia de g\u00e9nero.<\/p>\n<p>FUENTE: INFOCIELO<\/p>\n<div id=\"lanus-190935921\" class=\"lanus-despues-del-contenido\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7711057628815647\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:inline-block;width:0px;height:0px;\" \ndata-ad-client=\"ca-pub-7711057628815647\" \ndata-ad-slot=\"\"><\/ins> \n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Ocurri\u00f3 en las calles Jos\u00e9 Le\u00f3n Su\u00e1rez y Dardo Rocha. La v\u00edctima del femicido fue identificada como Anal\u00eda Gauna, de 46 a\u00f1os. El agresor, dos &#8230; <a title=\"LOCURA EN LANUS: MATO A SU MUJER Y SE SUICIDO\" class=\"read-more\" href=\"https:\/\/www.lanusnoticias.com.ar\/web\/lucura-en-lanus-mato-a-su-mujer-y-se-suicido\/\" aria-label=\"Leer m\u00e1s sobre LOCURA EN LANUS: MATO A SU MUJER Y SE SUICIDO\">Seguir Leyendo<\/a><\/p>\n","protected":false},"author":1,"featured_media":52720,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[278,24,41],"tags":[],"class_list":["post-52719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ahora","category-noticias-locales","category-policiales","infinite-scroll-item","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/52719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=52719"}],"version-history":[{"count":2,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/52719\/revisions"}],"predecessor-version":[{"id":52722,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/52719\/revisions\/52722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/52720"}],"wp:attachment":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=52719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=52719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=52719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}