{"id":54183,"date":"2019-06-19T17:09:17","date_gmt":"2019-06-19T20:09:17","guid":{"rendered":"https:\/\/www.lanusnoticias.com.ar\/web\/?p=54183"},"modified":"2019-06-19T17:09:17","modified_gmt":"2019-06-19T20:09:17","slug":"ojeda-las-encuestas-indican-que-el-que-mas-mide-es-julian-alvarez","status":"publish","type":"post","link":"https:\/\/www.lanusnoticias.com.ar\/web\/ojeda-las-encuestas-indican-que-el-que-mas-mide-es-julian-alvarez\/","title":{"rendered":"OJEDA: \u201cLAS ENCUESTAS INDICAN QUE EL QUE M\u00c1S MIDE ES JULI\u00c1N \u00c1LVAREZ\u201d."},"content":{"rendered":"<p>Juli\u00e1n Ojeda, dirigente del Frente Territorial Peronista inform\u00f3 a este Medio que decidi\u00f3 bajar su candidatura en apoyo a Juli\u00e1n \u00c1lvarez, a quien calific\u00f3 como la renovaci\u00f3n que Lan\u00fas necesita.<\/p>\n<p>Ojeda explic\u00f3: \u201cDecidimos apoyar a Juli\u00e1n \u00c1lvarez, y lo hicimos a\u00a0 trav\u00e9s de un comunicado que produjo un contagio en otros dirigentes. Celebro que los compa\u00f1eros y pre candidatos se hayan prestado a favor de la candidatura de Juli\u00e1n\u201d<\/p>\n<p>\u201cNos despojamos de la soberbia que yo critiqu\u00e9, y qued\u00f3 dividido entre Edgardo Depetri y Juli\u00e1n \u00c1lvarez, aunque \u00a0las encuestas indican que el que m\u00e1s mide es Juli\u00e1n \u00c1lvarez, \u00a0supongo que se va a terminar de definir el viernes\u201d<\/p>\n<p>Sobre si habr\u00e1 \u00a0Paso en el distrito expres\u00f3: \u201cNo s\u00e9 si iremos a las Paso o presentaremos una lista de unidad, yo s\u00e9 que Juli\u00e1n est\u00e1 trabajando para\u00a0 ser amplio por eso muchos dirigentes nos acercamos a \u00e9l\u201d<\/p>\n<p>\u201cCuando habl\u00e9 con Juli\u00e1n\u00a0 lo primero que hizo fue demostrar una fuerte autocritica, luego debatimos\u00a0 ideas, proyectos, no cargos. El tema central es c\u00f3mo vamos a reconstruir Lan\u00fas post\u00a0 Cambiemos\u201d<\/p>\n<p>Y destac\u00f3: \u201cJuli\u00e1n representa la renovaci\u00f3n, la renovaci\u00f3n dirigencial que el pueblo de Lan\u00fas pide, por eso lo acompa\u00f1amos.\u00a0 Nosotros le vamos a aportar el peronismo ortodoxo que necesita Lan\u00fas tiene futuro. Somos un grupo formado por organizaciones sociales, gremiales\u201d<\/p>\n<p>\u201cLos \u00fanicos que tenemos la capacidad, por nivel de imagen y de conocimiento,\u00a0 de pelearle \u00a0el lugar a Grindetti somos nosotros\u201d, manifest\u00f3 el dirigente peronista.<\/p>\n<p>Al finalizar sostuvo: \u201cYo siempre pido que la superestructura mire, escuche y sepa que ac\u00e1 estamos buscando una renovaci\u00f3n dirigencial, si no se logra una lista de unidad usaremos la herramienta que puso el kirchnerismo: que es las Paso. Las Paso en Lan\u00fas son sanadoras, no\u00a0 nos debemos ajustar al capricho de una persona sino a la realidad, y la realidad indica que la persona que m\u00e1s mide hoy es Juli\u00e1n \u00c1lvarez\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div id=\"lanus-465582485\" class=\"lanus-despues-del-contenido\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7711057628815647\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:inline-block;width:0px;height:0px;\" \ndata-ad-client=\"ca-pub-7711057628815647\" \ndata-ad-slot=\"\"><\/ins> \n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Juli\u00e1n Ojeda, dirigente del Frente Territorial Peronista inform\u00f3 a este Medio que decidi\u00f3 bajar su candidatura en apoyo a Juli\u00e1n \u00c1lvarez, a quien calific\u00f3 como &#8230; <a title=\"OJEDA: \u201cLAS ENCUESTAS INDICAN QUE EL QUE M\u00c1S MIDE ES JULI\u00c1N \u00c1LVAREZ\u201d.\" class=\"read-more\" href=\"https:\/\/www.lanusnoticias.com.ar\/web\/ojeda-las-encuestas-indican-que-el-que-mas-mide-es-julian-alvarez\/\" aria-label=\"Leer m\u00e1s sobre OJEDA: \u201cLAS ENCUESTAS INDICAN QUE EL QUE M\u00c1S MIDE ES JULI\u00c1N \u00c1LVAREZ\u201d.\">Seguir Leyendo<\/a><\/p>\n","protected":false},"author":1,"featured_media":51671,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-54183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-locales","infinite-scroll-item","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/54183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=54183"}],"version-history":[{"count":1,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/54183\/revisions"}],"predecessor-version":[{"id":54184,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/54183\/revisions\/54184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/51671"}],"wp:attachment":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=54183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=54183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=54183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}