{"id":55330,"date":"2019-09-11T21:49:40","date_gmt":"2019-09-12T00:49:40","guid":{"rendered":"https:\/\/www.lanusnoticias.com.ar\/web\/?p=55330"},"modified":"2019-09-11T21:49:40","modified_gmt":"2019-09-12T00:49:40","slug":"le-piden-a-vidal-que-de-una-vez-por-todas-informe-en-que-gasto-el-presupuesto-2018","status":"publish","type":"post","link":"https:\/\/www.lanusnoticias.com.ar\/web\/le-piden-a-vidal-que-de-una-vez-por-todas-informe-en-que-gasto-el-presupuesto-2018\/","title":{"rendered":"LE PIDEN A VIDAL QUE \u201cDE UNA VEZ POR TODAS INFORME EN QU\u00c9 GAST\u00d3 EL PRESUPUESTO 2018\u201d"},"content":{"rendered":"<p>La senadora provincial de Unidad Ciudadana, Teresa Garc\u00eda reclam\u00f3 al Ejecutivo bonaerense que informe la rendici\u00f3n de gastos correspondiente a 2018, ya que se encuentran vencidos todos los plazos. En ese sentido, advirti\u00f3 que de no recibir el detalle correspondiente iniciar\u00e1 las acciones por la violaci\u00f3n a la Ley de Acceso a la Informaci\u00f3n p\u00fablica.<\/p>\n<p>Seg\u00fan se inform\u00f3 desde el bloque de senadores de Unidad Ciudadana, la titular del mismo, la senadora Teresa Garc\u00eda (foto), \u00a0requiri\u00f3 por escrito al Ministro de Econom\u00eda de la provincia, Dami\u00e1n Bonari y al Contador General Carlos Baleztena, que presenten el \u201cinforme de Ejecuci\u00f3n Presupuestaria 2018\u201d.<\/p>\n<p>Garc\u00eda explic\u00f3 que \u201cen el informe Fiscal 2018 al que se puede acceder en la web de la Contadur\u00eda General de la Provincia falta la informaci\u00f3n referida al an\u00e1lisis por finalidad y funci\u00f3n del gasto que deber\u00eda contender un an\u00e1lisis sobre el destino del incremento del gasto\u201d. En ese orden tambi\u00e9n reclam\u00f3 \u201cel informe de ejecuci\u00f3n del cierre del Ejercicio 2018\u201d.<\/p>\n<p>Garc\u00eda remarc\u00f3: \u201cLe pedimos a Vidal que de una vez por todas informe en qu\u00e9 gast\u00f3 el Presupuesto de la provincia durante 2018\u201d. \u201cComo todos los plazos est\u00e1n vencidos y el Ejecutivo s\u00f3lo present\u00f3 la rendici\u00f3n hasta septiembre de 2018, reclamamos que detallen c\u00f3mo se ejecut\u00f3 el gasto por dependencia\u201d.<\/p>\n<p>Por \u00faltimo, la legisladora de la Primera Secci\u00f3n Electoral, sostuvo que \u201cLa demora es llamativa sobre todo porque el gobierno de Mar\u00eda Eugenia Vidal se autoproclam\u00f3 \u201ctrasparente\u201d, ahora le estamos pidiendo que sencillamente cumpla con la ley e informe cu\u00e1nto y c\u00f3mo gast\u00f3 el Presupuesto que le aprob\u00f3 la Legislatura para 2018\u201d, finaliz\u00f3 Garc\u00eda.\u00a0(<b>InfoGEI<\/b>)Jd<\/p>\n<div id=\"lanus-2496450320\" class=\"lanus-despues-del-contenido\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7711057628815647\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:inline-block;width:0px;height:0px;\" \ndata-ad-client=\"ca-pub-7711057628815647\" \ndata-ad-slot=\"\"><\/ins> \n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La senadora provincial de Unidad Ciudadana, Teresa Garc\u00eda reclam\u00f3 al Ejecutivo bonaerense que informe la rendici\u00f3n de gastos correspondiente a 2018, ya que se encuentran &#8230; <a title=\"LE PIDEN A VIDAL QUE \u201cDE UNA VEZ POR TODAS INFORME EN QU\u00c9 GAST\u00d3 EL PRESUPUESTO 2018\u201d\" class=\"read-more\" href=\"https:\/\/www.lanusnoticias.com.ar\/web\/le-piden-a-vidal-que-de-una-vez-por-todas-informe-en-que-gasto-el-presupuesto-2018\/\" aria-label=\"Leer m\u00e1s sobre LE PIDEN A VIDAL QUE \u201cDE UNA VEZ POR TODAS INFORME EN QU\u00c9 GAST\u00d3 EL PRESUPUESTO 2018\u201d\">Seguir Leyendo<\/a><\/p>\n","protected":false},"author":1,"featured_media":44969,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[144],"tags":[],"class_list":["post-55330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-nacionales-buenos-aires","infinite-scroll-item","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/55330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=55330"}],"version-history":[{"count":1,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/55330\/revisions"}],"predecessor-version":[{"id":55331,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/55330\/revisions\/55331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/44969"}],"wp:attachment":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=55330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=55330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=55330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}