{"id":56518,"date":"2019-12-18T22:58:46","date_gmt":"2019-12-19T01:58:46","guid":{"rendered":"https:\/\/www.lanusnoticias.com.ar\/web\/?p=56518"},"modified":"2019-12-18T22:58:46","modified_gmt":"2019-12-19T01:58:46","slug":"segun-sentencia-judicial-la-rosa-podria-asumir-como-diputada-en-lugar-de-russo","status":"publish","type":"post","link":"https:\/\/www.lanusnoticias.com.ar\/web\/segun-sentencia-judicial-la-rosa-podria-asumir-como-diputada-en-lugar-de-russo\/","title":{"rendered":"SEG\u00daN SENTENCIA JUDICIAL: LA ROSA PODR\u00cdA ASUMIR COMO DIPUTADA EN LUGAR DE RUSSO"},"content":{"rendered":"<p>La dirigente del Gen, Mar\u00eda \u00c1ngela La Rosa (foto) en comunicaci\u00f3n telef\u00f3nica con Lan\u00fas Noticias inform\u00f3 sobre la sentencia \u00a0en relaci\u00f3n a la banca de la diputada Blanca Cantero.<\/p>\n<p>La Rosa manifest\u00f3: \u201cSali\u00f3 la sentencia, ahora debe expedirse la C\u00e1mara legislativa, Nicolas Russo seguramente va a apelar. A nosotros nos dijeron que debemos esperar, seguramente se resuelve en estos d\u00edas\u201d<\/p>\n<p>\u201cEsta banca es el esfuerzo de mucha gente, dentro de un Partido que debemos salir adelante, entonces es importante para todos, sobre todo para las mujeres en todo sentido, en todas las \u00e1reas. Por el momento Russo est\u00e1 en la banca y tiene un amparo, donde no puede hacer mucho, los dos queremos la banca. A nosotros nos corresponde por la paridad de g\u00e9nero, que fue aprobada hace dos a\u00f1os en provincia\u201d, finaliz\u00f3 la ex concejala.<\/p>\n<div id=\"lanus-937984113\" class=\"lanus-despues-del-contenido\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7711057628815647\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:inline-block;width:0px;height:0px;\" \ndata-ad-client=\"ca-pub-7711057628815647\" \ndata-ad-slot=\"\"><\/ins> \n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La dirigente del Gen, Mar\u00eda \u00c1ngela La Rosa (foto) en comunicaci\u00f3n telef\u00f3nica con Lan\u00fas Noticias inform\u00f3 sobre la sentencia \u00a0en relaci\u00f3n a la banca de &#8230; <a title=\"SEG\u00daN SENTENCIA JUDICIAL: LA ROSA PODR\u00cdA ASUMIR COMO DIPUTADA EN LUGAR DE RUSSO\" class=\"read-more\" href=\"https:\/\/www.lanusnoticias.com.ar\/web\/segun-sentencia-judicial-la-rosa-podria-asumir-como-diputada-en-lugar-de-russo\/\" aria-label=\"Leer m\u00e1s sobre SEG\u00daN SENTENCIA JUDICIAL: LA ROSA PODR\u00cdA ASUMIR COMO DIPUTADA EN LUGAR DE RUSSO\">Seguir Leyendo<\/a><\/p>\n","protected":false},"author":1,"featured_media":56113,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[278,24],"tags":[],"class_list":["post-56518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ahora","category-noticias-locales","infinite-scroll-item","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/56518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=56518"}],"version-history":[{"count":1,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/56518\/revisions"}],"predecessor-version":[{"id":56519,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/56518\/revisions\/56519"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/56113"}],"wp:attachment":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=56518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=56518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=56518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}