{"id":61765,"date":"2021-01-31T18:18:36","date_gmt":"2021-01-31T21:18:36","guid":{"rendered":"https:\/\/www.lanusnoticias.com.ar\/web\/?p=61765"},"modified":"2021-01-31T18:18:36","modified_gmt":"2021-01-31T21:18:36","slug":"juntos-por-el-cambio-repudio-el-uso-politico-de-la-campana-de-vacunacion-contra-el-coronavirus-llevado-adelante-por-la-campora","status":"publish","type":"post","link":"https:\/\/www.lanusnoticias.com.ar\/web\/juntos-por-el-cambio-repudio-el-uso-politico-de-la-campana-de-vacunacion-contra-el-coronavirus-llevado-adelante-por-la-campora\/","title":{"rendered":"JUNTOS POR EL CAMBIO REPUDI\u00d3 EL USO POL\u00cdTICO DE LA CAMPA\u00d1A DE VACUNACI\u00d3N CONTRA EL CORONAVIRUS LLEVADO ADELANTE POR LA CAMPORA"},"content":{"rendered":"<p>El Ejecutivo de Lan\u00fas no escapa al rechazo generalizado que existe, desde la Oposici\u00f3n, por el uso pol\u00edtico que se le da a la inscripci\u00f3n de la vacuna Sputnik V contra el covid 19 en la provincia de Buenos Aires, a trav\u00e9s de la C\u00e1mpora .<\/p>\n<p>Se utilizan los locales de las agrupaciones como centros de informaci\u00f3n para la vacunaci\u00f3n de la sociedad, cuando es un tema de salud p\u00fablica, con recursos del Estado.<\/p>\n<p>La Oposici\u00f3n considera que el Gobierno nacional y provincial deber\u00edan despolitizar las cuestiones relacionadas a la inmunidad de la poblaci\u00f3n. La estrategia de vacunaci\u00f3n debe ser del sistema de salud, no de un partido pol\u00edtico, ya que la vacuna no es una pol\u00edtica partidaria.<\/p>\n<p>Por su parte, N\u00e9stor Grindetti, en su twitter, public\u00f3 el comunicado de Juntos por el Cambio, donde repudia la utilizaci\u00f3n\u00a0 partidaria del plan de vacunaci\u00f3n, que llevan adelante algunos dirigentes del Frente de Todos, argumentando que es un proceso que deber\u00eda ser exclusivo del Estado en sus tres niveles de gobierno, nacional, provincial y municipal.<\/p>\n<p>Los niveles del Estado cuentan con las herramientas para acompa\u00f1ar a las familias que no tienen acceso a la informaci\u00f3n y sostiene que estas pr\u00e1cticas atentan contra el rol de las instituciones.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div id=\"lanus-2963846968\" class=\"lanus-despues-del-contenido\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7711057628815647\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:inline-block;width:0px;height:0px;\" \ndata-ad-client=\"ca-pub-7711057628815647\" \ndata-ad-slot=\"\"><\/ins> \n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>El Ejecutivo de Lan\u00fas no escapa al rechazo generalizado que existe, desde la Oposici\u00f3n, por el uso pol\u00edtico que se le da a la inscripci\u00f3n &#8230; <a title=\"JUNTOS POR EL CAMBIO REPUDI\u00d3 EL USO POL\u00cdTICO DE LA CAMPA\u00d1A DE VACUNACI\u00d3N CONTRA EL CORONAVIRUS LLEVADO ADELANTE POR LA CAMPORA\" class=\"read-more\" href=\"https:\/\/www.lanusnoticias.com.ar\/web\/juntos-por-el-cambio-repudio-el-uso-politico-de-la-campana-de-vacunacion-contra-el-coronavirus-llevado-adelante-por-la-campora\/\" aria-label=\"Leer m\u00e1s sobre JUNTOS POR EL CAMBIO REPUDI\u00d3 EL USO POL\u00cdTICO DE LA CAMPA\u00d1A DE VACUNACI\u00d3N CONTRA EL CORONAVIRUS LLEVADO ADELANTE POR LA CAMPORA\">Seguir Leyendo<\/a><\/p>\n","protected":false},"author":1,"featured_media":61766,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[278,24,37],"tags":[],"class_list":["post-61765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ahora","category-noticias-locales","category-noticias-nacionales-politica","infinite-scroll-item","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/61765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/comments?post=61765"}],"version-history":[{"count":1,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/61765\/revisions"}],"predecessor-version":[{"id":61767,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/posts\/61765\/revisions\/61767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/media\/61766"}],"wp:attachment":[{"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/media?parent=61765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/categories?post=61765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lanusnoticias.com.ar\/web\/wp-json\/wp\/v2\/tags?post=61765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}